{"id":1288,"date":"2024-02-18T09:34:29","date_gmt":"2024-02-18T08:34:29","guid":{"rendered":"https:\/\/mont-saint-michel.jfguillou.fr\/?p=1288"},"modified":"2024-02-18T09:35:18","modified_gmt":"2024-02-18T08:35:18","slug":"les-oies-bernaches-de-la-baie-du-mont-saint-michel","status":"publish","type":"post","link":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/2024\/02\/18\/les-oies-bernaches-de-la-baie-du-mont-saint-michel\/","title":{"rendered":"Les oies bernaches de la baie du Mont Saint-Michel"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Les-oies-bernaches-de-la-baie-du-Mont-Saint-Michel-Thalassa1.mp4\"><\/video><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.youtube.com\/hashtag\/thalassa\">Thalassa<\/a> \/ <a href=\"https:\/\/www.youtube.com\/redirect?event=video_description&amp;redir_token=QUFFLUhqbGhUNENZRmtOMl9TUGV5aDRKdlU5S3l6OWFzQXxBQ3Jtc0tra3JZSHhGU2gzTGRYM2tYX1ZxNWdHd2FBVTJ2MDNlV1haY2xVZU1hbXc2WUpXZlZrWTdCNFotLTlaZkd4WGpGRzctLTRpYXdadzhvS3ZNeFhXZnJydUtQaTZYZk1KY01pai1fVU55T1E5Mk9EVGNodw&amp;q=https%3A%2F%2Fwww.france.tv%2Ffrance-3%2Fthalassa%2F&amp;v=DvGwDxcE2OY\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.france.tv\/france-3\/thalassa\/<\/a> <br>Ici, la Nature et l\u2019Homme se sont alli\u00e9s pour le meilleur ! Depuis plus de dix si\u00e8cles le Mont Saint-Michel \u00ab\u00a0envo\u00fbte\u00a0\u00bb ceux qui l\u2019approchent. Visiteurs d\u2019un jour ou r\u00e9sidents de la baie, tous ob\u00e9issent \u00e0 la v\u00e9ritable maitresse des lieux : la mar\u00e9e !<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_jetpack_memberships_contains_paid_content":false},"categories":[4],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288"}],"collection":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1288"}],"version-history":[{"count":1,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions"}],"predecessor-version":[{"id":1290,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions\/1290"}],"wp:attachment":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}