{"id":1247,"date":"2024-02-11T17:26:01","date_gmt":"2024-02-11T16:26:01","guid":{"rendered":"https:\/\/mont-saint-michel.jfguillou.fr\/?p=1247"},"modified":"2024-02-18T09:35:05","modified_gmt":"2024-02-18T08:35:05","slug":"archives-ina-les-pecheries-de-la-baie-du-mont-saint-michel-2004","status":"publish","type":"post","link":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/2024\/02\/11\/archives-ina-les-pecheries-de-la-baie-du-mont-saint-michel-2004\/","title":{"rendered":"Archives INA : Les p\u00eacheries de la baie du Mont Saint-Michel (2004)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ina.fr\/ina-eclaire-actu\/video\/rn00001383889\/gros-plan-les-pecheries-de-la-baie-du-mont-saint-michel\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04-1024x686.jpg\" alt=\"\" class=\"wp-image-1248\" srcset=\"https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04-1024x686.jpg 1024w, https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04-300x201.jpg 300w, https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04-768x514.jpg 768w, https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04-75x50.jpg 75w, https:\/\/mont-saint-michel.jfguillou.fr\/wp-content\/uploads\/2024\/02\/Capture-decran-2024-02-11-a-17.24.04.jpg 1460w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Sur 40 p\u00eacheries qui existaient autrefois dans la baie du Mont Saint Michel, une 20aine sont toujours exploit\u00e9es. Ce proc\u00e9d\u00e9 de p\u00eache traditionnelle exige beaucoup de temps de restauration et d&rsquo;entretien. Rencontre avec Ren\u00e9e et son mari qui \u00e0 chaque mar\u00e9e viennent r\u00e9colter le poisson (maquereau, sole, bar, turbot\u2026) dans leur p\u00eacherie. La Maison de la baie organise des sorties pour expliquer ce mode de p\u00eache aux touristes et pr\u00e9senter aussi l&rsquo;activit\u00e9 principale de la baie : la mytiliculture.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_jetpack_memberships_contains_paid_content":false},"categories":[4],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1247"}],"collection":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":2,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions"}],"predecessor-version":[{"id":1250,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions\/1250"}],"wp:attachment":[{"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mont-saint-michel.jfguillou.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}